{"id":20022,"date":"2024-12-23T06:58:00","date_gmt":"2024-12-22T22:58:00","guid":{"rendered":"https:\/\/steelprogroup.com\/?p=20022"},"modified":"2024-12-23T15:50:44","modified_gmt":"2024-12-23T07:50:44","slug":"heat-treatment","status":"publish","type":"post","link":"https:\/\/steelprogroup.com\/de\/tool-steel\/grades\/h13\/manufacturing\/heat-treatment\/","title":{"rendered":"W\u00e4rmebehandlung von H13-Werkzeugstahl: Ein Leitfaden der SteelPro Group"},"content":{"rendered":"<p>Bei SteelPro Group bieten wir H13-Stahlprodukte im gegl\u00fchten Zustand an, sodass Sie schnell mit den n\u00e4chsten Schritten Ihres Projekts fortfahren k\u00f6nnen. Dar\u00fcber hinaus unterst\u00fctzen wir Sie bei Mischkristallbehandlungen, Vorh\u00e4rtung und anderen W\u00e4rmebehandlungsanforderungen, um sicherzustellen, dass Ihr Stahl die genau erforderlichen Spezifikationen erf\u00fcllt.<\/p><h2 class=\"wp-block-heading\">W\u00e4rmebehandlungsprozess f\u00fcr H13-Werkzeugstahl<\/h2><h3 class=\"wp-block-heading\">Gl\u00fchen<\/h3><p><strong>Prozess:<\/strong><\/p><ul class=\"wp-block-list\"><li>Mit einer Rate von 222\u00a0\u00b0C (400\u00a0\u00b0F) pro Stunde auf 857\u2013885\u00a0\u00b0C (1575\u20131625\u00a0\u00b0F) erhitzen.<\/li>\n\n<li>Halten Sie die Schicht 1 Stunde lang pro 25,44 mm (1 Zoll) Dicke (mindestens 2 Stunden).<\/li>\n\n<li>Langsames Abk\u00fchlen im Ofen bei nicht mehr als 28\u00a0\u00b0C (50\u00a0\u00b0F) pro Stunde, bis 538\u00a0\u00b0C (1000\u00a0\u00b0F) erreicht sind, dann an der Luft auf Raumtemperatur abk\u00fchlen lassen.<\/li><\/ul><p><strong>Funktion:<\/strong><\/p><p>Durch langsames Erhitzen und Abk\u00fchlen stabilisiert sich die Kristallstruktur, wodurch die H\u00e4rte abnimmt, die Duktilit\u00e4t zunimmt und die Bearbeitbarkeit verbessert wird. Dieser Prozess f\u00f6rdert eine gleichm\u00e4\u00dfige Kornstruktur und minimiert das Risiko von Verformungen oder Rissen in sp\u00e4teren Phasen. Im Wesentlichen verbessert das Gl\u00fchen die Bearbeitbarkeit des Materials und bereitet es auf den H\u00e4rtungsprozess vor.<\/p><h3 class=\"wp-block-heading\">Aush\u00e4rtung<\/h3><h4 class=\"wp-block-heading\">Vorw\u00e4rmen<\/h4><p><strong>Prozess<\/strong>:<\/p><ul class=\"wp-block-list\"><li>F\u00fcr komplexe Formen: Mit nicht mehr als 222\u00a0\u00b0C (400\u00a0\u00b0F) pro Stunde auf 621\u2013677\u00a0\u00b0C (1150\u20131250\u00a0\u00b0F) vorheizen, dann gleichm\u00e4\u00dfig auf 816\u2013871\u00a0\u00b0C (1500\u20131600\u00a0\u00b0F) erhitzen.<\/li>\n\n<li>F\u00fcr einfachere Formen: Direkt auf 816\u2013871\u00a0\u00b0C (1500\u20131600\u00a0\u00b0F) erhitzen.<\/li><\/ul><p><strong>Funktion<\/strong>:<\/p><p>Durch das Vorw\u00e4rmen wird eine gleichm\u00e4\u00dfige Temperaturverteilung im Stahl gew\u00e4hrleistet und das Risiko eines Thermoschocks, insbesondere bei komplizierteren Formen, minimiert. Durch langsames Erhitzen im Anfangsstadium kann sich der Stahl allm\u00e4hlich ausdehnen, wodurch die Gefahr von Rissen oder Verformungen w\u00e4hrend der nachfolgenden Hochtemperaturprozesse verringert wird.<\/p><h4 class=\"wp-block-heading\">Austenitisierung<\/h4><p><strong>Prozess<\/strong>:<\/p><ul class=\"wp-block-list\"><li>Auf 982\u20131032\u00a0\u00b0C (1800\u20131900\u00a0\u00b0F) erhitzen.<\/li>\n\n<li>Halten Sie es 1 Stunde lang pro 25,44 mm (1 Zoll) Dicke bei der gew\u00fcnschten Temperatur.<\/li><\/ul><p><strong>Funktion<\/strong>:<\/p><p>Durch das Austenitisieren kann Kohlenstoff diffundieren und Carbide k\u00f6nnen sich aufl\u00f6sen, was H\u00e4rte und Verschlei\u00dffestigkeit verbessert. Bei niedrigeren Temperaturen steht die Z\u00e4higkeit im Vordergrund. Bei h\u00f6heren Temperaturen maximieren wir die H\u00e4rte. Das Halten der Temperatur des Materials gew\u00e4hrleistet eine gleichm\u00e4\u00dfige Umwandlung im gesamten Stahl.<\/p><h4 class=\"wp-block-heading\">Abschrecken<\/h4><p><strong>Prozess:<\/strong><\/p><ul class=\"wp-block-list\"><li>Zum Abschrecken in Luft k\u00fchlen Sie H13-Werkzeugstahl in einem Druckluftstrom mit einer Geschwindigkeit von ungef\u00e4hr 10\u201320\u00a0\u00b0C (50\u201370\u00a0\u00b0F) pro Sekunde ab.<\/li>\n\n<li>Beim Abschrecken mit \u00d6l ist darauf zu achten, dass das Abschreckmedium die richtige Temperatur hat (ca. 40\u201360\u00a0\u00b0C).<\/li><\/ul><p><strong>Funktion<\/strong>:<\/p><p>Durch Abschrecken wird H13 schnell von Austenitisierungstemperaturen abgek\u00fchlt, in Martensit umgewandelt und die H\u00e4rte erh\u00f6ht. Luftabschrecken sorgt f\u00fcr langsameres Abk\u00fchlen und reduziert thermische Spannungen und Verformungen, w\u00e4hrend \u00d6labschrecken schnelleres Abk\u00fchlen bietet und zu h\u00f6herer H\u00e4rte, aber erh\u00f6hten inneren Spannungen f\u00fchrt. Die Wahl des Abschreckmediums h\u00e4ngt von der Geometrie und den gew\u00fcnschten Eigenschaften ab.<\/p><h3 class=\"wp-block-heading\">Anlassen<\/h3><p><strong>Prozess:<\/strong><\/p><ul class=\"wp-block-list\"><li>Auf 540\u2013620\u00a0\u00b0C (1000\u20131150\u00a0\u00b0F) erhitzen.<\/li>\n\n<li>1\u20132 Stunden halten, dann an der Luft abk\u00fchlen lassen.<\/li><\/ul><p><strong>Zweimal temperieren<\/strong> nach dem Abschrecken. Dieser Schritt hilft, Spannungen abzubauen und stellt sicher, dass Ihre Teile nicht zu spr\u00f6de werden. F\u00fcr die meisten Anwendungen ist ein Anlassen bei 500\u2013600 \u00b0C (932\u20131112 \u00b0F) f\u00fcr 1\u20132 Stunden gut geeignet.<\/p><p><strong>Funktion<\/strong>:<\/p><p>Durch das Anlassen wird die Spr\u00f6digkeit verringert, da sich Martensit in eine stabilere Mikrostruktur umwandeln kann. Dies verbessert die Z\u00e4higkeit und baut Spannungen durch Abschrecken ab, w\u00e4hrend die wesentliche H\u00e4rte erhalten bleibt.&nbsp;<\/p><h3 class=\"wp-block-heading\">K\u00e4ltebehandlung<\/h3><h4 class=\"wp-block-heading\">Niedertemperaturbehandlung<\/h4><p><strong>Prozess:<\/strong><\/p><ul class=\"wp-block-list\"><li>Der Stahl wird auf Temperaturen zwischen -70\u00b0C und -80\u00b0C abgek\u00fchlt.<\/li>\n\n<li>Anschlie\u00dfend wird es je nach Gr\u00f6\u00dfe und Komplexit\u00e4t des Teils 12 bis 24 Stunden bei dieser Temperatur eingeweicht.<\/li>\n\n<li>Nach dem Einweichen wird der Stahl langsam wieder auf Raumtemperatur erw\u00e4rmt, um einen Thermoschock zu vermeiden.<\/li><\/ul><p><strong>Funktion:<\/strong><\/p><p>Diese Behandlung hilft, innere Spannungen abzubauen, die sich w\u00e4hrend fr\u00fcherer Prozesse wie H\u00e4rten, Bearbeiten oder Schwei\u00dfen aufbauen k\u00f6nnen, und verhindert so Risse oder Verformungen. Au\u00dferdem erh\u00f6ht sie die W\u00e4rmeerm\u00fcdungsbest\u00e4ndigkeit, was f\u00fcr Teile wie Formen und Matrizen wichtig ist.<\/p><h4 class=\"wp-block-heading\">Kryogenische Behandlung<\/h4><p><strong>Prozess:<\/strong><\/p><ul class=\"wp-block-list\"><li>Der Stahl wird mit fl\u00fcssigem Stickstoff auf extrem niedrige Temperaturen von -196\u00b0C abgek\u00fchlt.<\/li>\n\n<li>Um eine gr\u00fcndliche Behandlung zu gew\u00e4hrleisten, wird es 24 bis 48 Stunden bei dieser Temperatur eingeweicht.<\/li>\n\n<li>Nach dem Einweichen wird das Material langsam wieder auf Umgebungstemperatur gebracht, um Sch\u00e4den zu vermeiden.<\/li><\/ul><p><strong>Funktion:<\/strong><\/p><p>Durch die kryogene Verarbeitung wird Restaustenit in Martensit umgewandelt, was die H\u00e4rte und Abriebfestigkeit verbessert. Au\u00dferdem verbessert es die Dimensionsstabilit\u00e4t, verringert das Rissrisiko und erh\u00f6ht die Z\u00e4higkeit und Erm\u00fcdungsbest\u00e4ndigkeit, wodurch H13 in anspruchsvollen Anwendungen langlebiger wird.<\/p><h2 class=\"wp-block-heading\">W\u00e4rmebehandlungsempfehlungen f\u00fcr H13-Stahlanwendungen<\/h2><p>Bei SteelPro Group geben wir Ihnen fachkundige Empfehlungen, um sicherzustellen, dass Ihr H13-Werkzeugstahl Ihren spezifischen Anforderungen optimal gerecht wird. Hier ist ein \u00dcberblick \u00fcber die beste Vorgehensweise f\u00fcr verschiedene Anwendungen:<\/p><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Anmeldung<\/strong><\/td><td><strong>Gl\u00fchen<\/strong><\/td><td><strong>Aush\u00e4rtung<\/strong><\/td><td><strong>Anlassen<\/strong><\/td><td><strong>Vorh\u00e4rten<\/strong><\/td><td><strong>Stressabbau<\/strong><\/td><\/tr><tr><td>Druckgussformen<\/td><td>\u221a<\/td><td>\u221a<\/td><td>\u221a<\/td><td><\/td><td><\/td><\/tr><tr><td>Kunststoff-Formwerkzeuge<\/td><td><\/td><td><\/td><td>\u221a<\/td><td>\u221a<\/td><td><\/td><\/tr><tr><td>Gesenke f\u00fcr Warmschmiedearbeiten<\/td><td><\/td><td>\u221a<\/td><td>\u221a<\/td><td><\/td><td>\u221a<\/td><\/tr><\/tbody><\/table><\/figure><p>F\u00fcr eine individuelle W\u00e4rmebehandlungsberatung wenden Sie sich an unsere Experten bei der SteelPro Group. Wir haben an zahlreichen Projekten gearbeitet, von Druckgussformen bis hin zu Warmschmiedegesenken, und unseren Kunden geholfen, optimale Ergebnisse mit H13-Werkzeugstahl zu erzielen. Lassen Sie sich von uns zur optimalen W\u00e4rmebehandlung f\u00fcr Ihren H13-Werkzeugstahl beraten.<\/p><h2 class=\"wp-block-heading\">Holen Sie sich pr\u00e4zisionsgefertigten H13-Werkzeugstahl f\u00fcr Ihr Projekt<\/h2><p>Wir bieten eine breite Palette von <a href=\"https:\/\/steelprogroup.com\/de\/tool-steel\/h13\/\">H13 Werkzeugstahlprodukte<\/a> in verschiedenen Formen, einschlie\u00dflich Stangen, Platten und Sonderabmessungen. Unsere W\u00e4rmebehandlungsprozesse werden sorgf\u00e4ltig kontrolliert, um pr\u00e4zise Ergebnisse f\u00fcr verbesserte Festigkeit, Haltbarkeit und Leistung zu gew\u00e4hrleisten.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>At SteelPro Group, we offer H13 steel products in annealing conditions, allowing you to move quickly into the next steps [&hellip;]<\/p>","protected":false},"author":12,"featured_media":19989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","rank_math_lock_modified_date":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4300,4294,4296,4293],"tags":[],"class_list":["post-20022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manufacturing-h13","category-grades-tool-steel","category-h13","category-tool-steel"],"acf":[],"_links":{"self":[{"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/posts\/20022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/comments?post=20022"}],"version-history":[{"count":0,"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/posts\/20022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/media\/19989"}],"wp:attachment":[{"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/media?parent=20022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/categories?post=20022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/steelprogroup.com\/de\/wp-json\/wp\/v2\/tags?post=20022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}