{"id":21787,"date":"2025-04-02T03:27:00","date_gmt":"2025-04-01T19:27:00","guid":{"rendered":"https:\/\/steelprogroup.com\/?p=21787"},"modified":"2025-03-31T11:09:43","modified_gmt":"2025-03-31T03:09:43","slug":"aermet-100-guideline","status":"publish","type":"post","link":"https:\/\/steelprogroup.com\/pt\/alloy-steel\/aermet-100-guideline\/","title":{"rendered":"A\u00e7o AerMet 100 AMS 6532 | UNS K92580: Propriedades, Processos"},"content":{"rendered":"<p class=\"c7\"><span class=\"c16\">Em a\u00e7os de alto desempenho, poucos materiais alcan\u00e7am o equil\u00edbrio entre pot\u00eancia bruta e engenharia de precis\u00e3o como o a\u00e7o AerMet\u00ae 100. <\/span><\/p><p class=\"c7\"><span class=\"c16\">Este artigo analisa a ci\u00eancia, as aplica\u00e7\u00f5es e as vantagens exclusivas do a\u00e7o AerMet 100, revelando por que ele supera as ligas convencionais em ambientes de alto estresse. <\/span><\/p><h2 class=\"wp-block-heading c7 c14\" id=\"h.sovzh6gsi4ou\"><span class=\"c26\">O que \u00e9 o a\u00e7o AerMet 100?<\/span><\/h2><p class=\"c7\"><span class=\"c16\">O a\u00e7o AerMet 100 \u00e9 uma liga de ultra-alta resist\u00eancia projetada para estresse mec\u00e2nico extremo. Sua composi\u00e7\u00e3o de cobalto, n\u00edquel, cromo, molibd\u00eanio e carbono cria uma microestrutura dur\u00e1vel que tem bom desempenho sob cargas din\u00e2micas. A liga fornece excelente dureza, resist\u00eancia \u00e0 tra\u00e7\u00e3o e tenacidade \u00e0 fratura. Ele tamb\u00e9m ret\u00e9m a ductilidade e resiste \u00e0 corros\u00e3o sob tens\u00e3o. Com desempenho confi\u00e1vel de at\u00e9 800 \u00b0F (427 \u00b0C), o AerMet 100 \u00e9 usado em trens de pouso aeroespaciais, sistemas de blindagem e componentes de acionamento cr\u00edticos. A liga n\u00e3o requer pr\u00e9-aquecimento para soldagem, mas precisa de prote\u00e7\u00e3o em condi\u00e7\u00f5es \u00famidas devido \u00e0 resist\u00eancia limitada \u00e0 corros\u00e3o.<\/span><\/p><ul class=\"wp-block-list c22 lst-kix_9lssd537qip-0 start\"><li><span class=\"c3 c21\">AerMet<\/span><span class=\"c21\">\u00a0\u00e9 uma marca registrada da <\/span><span class=\"c3 c21\">Corpora\u00e7\u00e3o de Tecnologia de Carpinteiro<\/span><span class=\"c21\">.<\/span><\/li><\/ul><h2 class=\"wp-block-heading c7 c14\" id=\"h.qylfhs1ubm4c\"><span class=\"c26\">Especifica\u00e7\u00f5es do a\u00e7o AerMet 100<\/span><\/h2><p class=\"c7\"><span class=\"c16\">O a\u00e7o AerMet 100 atende aos rigorosos padr\u00f5es da ind\u00fastria, garantindo conformidade e confiabilidade.<\/span><\/p><ul class=\"wp-block-list c22 lst-kix_nowuevr0dl5h-0 start\"><li><span class=\"c16\">AMS 6478<\/span><\/li>\n\n<li><span class=\"c16\">AMS 6532<\/span><\/li>\n\n<li><span class=\"c16\">McDonnell Douglas MMS 217<\/span><\/li>\n\n<li><span class=\"c16\">MIL HDBK-5<\/span><\/li><\/ul><h3 class=\"wp-block-heading c7 c14\" id=\"h.ebgph28qlu3p\"><span class=\"c6\">Grau equivalente de a\u00e7o AerMet 100:<\/span><\/h3><ul class=\"wp-block-list c22 lst-kix_9lssd537qip-0\"><li><span>UNS K92580<\/span><\/li><\/ul><h2 class=\"wp-block-heading c7 c14\" id=\"h.ei826o403ifj\"><span class=\"c26\">Composi\u00e7\u00e3o qu\u00edmica do a\u00e7o AerMet 100<\/span><\/h2><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Elemento<\/strong><\/td><td><strong>Conte\u00fado<\/strong><\/td><\/tr><tr><td>Carbono (C)<\/td><td>0.21~0.25<\/td><\/tr><tr><td>Sil\u00edcio (Si)<\/td><td>\u22640.15<\/td><\/tr><tr><td>Mangan\u00eas (Mn)<\/td><td>\u22640.10<\/td><\/tr><tr><td>F\u00f3sforo (P)<\/td><td>\u22640.008<\/td><\/tr><tr><td>Enxofre (S)<\/td><td>\u22640,005<\/td><\/tr><tr><td>Cromo (Cr)<\/td><td>2.9~3.3<\/td><\/tr><tr><td>N\u00edquel (Ni)<\/td><td>11~12<\/td><\/tr><tr><td>Molibd\u00eanio (Mo)<\/td><td>1.1~1.3<\/td><\/tr><tr><td>Nitrog\u00eanio (N)<\/td><td>\u22640,0015<\/td><\/tr><tr><td>Tit\u00e2nio (Ti)<\/td><td>\u22640.015<\/td><\/tr><tr><td>Cobalto (Co)<\/td><td>13~14<\/td><\/tr><tr><td>Alum\u00ednio (Al)<\/td><td>\u22640.015<\/td><\/tr><tr><td>Oxig\u00eanio (O)<\/td><td>\u22640,002<\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading c7 c14\" id=\"h.aoaybovkfuj0\"><span class=\"c26\">Propriedades mec\u00e2nicas do a\u00e7o AerMet 100 (ap\u00f3s tratamento t\u00e9rmico)<\/span><\/h2><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Propriedade<\/strong><\/td><td><strong>Valor Longitudinal<\/strong><\/td><td><strong>Valor Transversal<\/strong><\/td><\/tr><tr><td>Limite de escoamento (deslocamento de 0,2%)<\/td><td>1720 MPa (250 ksi)<\/td><td>1720 MPa (250 ksi)<\/td><\/tr><tr><td>Resist\u00eancia \u00e0 tra\u00e7\u00e3o<\/td><td>1960 MPa (285 ksi)<\/td><td>1960 MPa (285 ksi)<\/td><\/tr><tr><td>Alongamento (%)<\/td><td>14%<\/td><td>13%<\/td><\/tr><tr><td>Redu\u00e7\u00e3o de \u00c1rea (%)<\/td><td>65%<\/td><td>55%<\/td><\/tr><tr><td>Energia de impacto Charpy V-Notch<\/td><td>41 J (30 p\u00e9s-lb)<\/td><td>34 J (25 p\u00e9s-lb)<\/td><\/tr><tr><td>Tenacidade \u00e0 fratura (K <sub>IC<\/sub> )<\/td><td>126 MPa\u221am (115 ksi\u221apol)<\/td><td>110 MPa\u221am (100 ksi\u221apol)<\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading c7 c14\" id=\"h.j0vyvkieyyzc\"><span class=\"c6\">Propriedades relacionadas \u00e0 temperatura<\/span><\/h3><ul class=\"wp-block-list c22 lst-kix_r296kavrpnr-0 start\"><li><span class=\"c3 c24\">Desempenho em alta temperatura<\/span><\/li><\/ul><p class=\"c7\"><span class=\"c16\">O AerMet 100 mant\u00e9m a estabilidade at\u00e9 427\u00b0C (800\u00b0F), mas sua resist\u00eancia \u00e0 tra\u00e7\u00e3o diminui gradualmente com o aumento da temperatura. Por exemplo, a 260\u00b0C (500\u00b0F), a resist\u00eancia \u00e0 tra\u00e7\u00e3o \u00e9 de aproximadamente 1650 MPa (240 ksi).<\/span><\/p><ul class=\"wp-block-list c22 lst-kix_v1cvwvgygcp5-0 start\"><li><span class=\"c24 c3\">Resist\u00eancia ao impacto em baixa temperatura<\/span><\/li><\/ul><p class=\"c7\"><span class=\"c16\">Mesmo a -73 \u00b0C (-100 \u00b0F), o AerMet 100 ret\u00e9m uma alta energia de impacto, aproximadamente 41 J (30 ft-lb), demonstrando sua excelente resist\u00eancia a baixas temperaturas.<\/span><\/p><h2 class=\"wp-block-heading c7 c14\" id=\"h.b5yts9exvwur\"><span class=\"c26\">Propriedades f\u00edsicas do a\u00e7o AerMet 100<\/span><\/h2><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Propriedade<\/strong><\/td><td><strong>Valor m\u00e9trico<\/strong><\/td><td><strong>Valor imperial<\/strong><\/td><\/tr><tr><td>Densidade<\/td><td>7,89 g\/cm\u00b3<\/td><td>0,285 lb\/in\u00b3<\/td><\/tr><tr><td>M\u00f3dulo de elasticidade<\/td><td>194,5 GPA<\/td><td>28,2\u00d710\u00b3 ksi<\/td><\/tr><tr><td>Resistividade (21\u00b0C\/70\u00b0F)<\/td><td>&#8211;<\/td><td>259 ohm-cir-mil\/p\u00e9<\/td><\/tr><tr><td>Temperatura cr\u00edtica (AC\u2081\/AC\u2083)<\/td><td>574\u00b0C \/ 829\u00b0C<\/td><td>1065\u00b0F \/ 1525\u00b0F<\/td><\/tr><tr><td rowspan=\"2\">Coeficiente de expans\u00e3o t\u00e9rmica (315,56 \u00b0C\/600 \u00b0F)<\/td><td>10,82\u00d710\u207b\u2076 m\/m\/\u00b0C (recozido)<\/td><td>6,01\u00d710\u207b\u2076 pol\/pol\/\u00b0F (recozido)<\/td><\/tr><tr><td>10,94\u00d710\u207b\u2076 m\/m\/\u00b0C (Tratado termicamente)<\/td><td>6,08\u00d710\u207b\u2076 pol\/pol\/\u00b0F (tratado termicamente)<\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading c7 c14\" id=\"h.drwqidqli630\"><span class=\"c26\">Especifica\u00e7\u00e3o de produtos de a\u00e7o AerMet 100<\/span><\/h2><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Formul\u00e1rio do produto<\/strong><\/td><td><strong>Dimens\u00e3o<\/strong><\/td><td><strong>Unidades m\u00e9tricas<\/strong><\/td><td><strong>Unidades imperiais<\/strong><\/td><\/tr><tr><td>Barras redondas<\/td><td>Di\u00e2metro<\/td><td>12,7 mm ~ 305 mm<\/td><td>0,5 pol ~ 12 pol<\/td><\/tr><tr><td rowspan=\"3\">Placa<\/td><td>Espessura<\/td><td>6,35 mm ~ 101,6 mm<\/td><td>0,25 pol ~ 4 pol<\/td><\/tr><tr><td>Largura<\/td><td>101,6 mm ~ 1219 mm<\/td><td>4 pol ~ 48 pol<\/td><\/tr><tr><td>Comprimento<\/td><td>305 mm ~ 6096 mm<\/td><td>12 pol ~ 240 pol<\/td><\/tr><tr><td rowspan=\"3\">Folha<\/td><td>Espessura<\/td><td>6,35 mm ~ 19,05 mm<\/td><td>0,25 pol ~ 0,75 pol<\/td><\/tr><tr><td>Largura<\/td><td>101,6 mm ~ 1219 mm<\/td><td>4 pol ~ 48 pol<\/td><\/tr><tr><td>Comprimento<\/td><td>305 mm ~ 6096 mm<\/td><td>12 pol ~ 240 pol<\/td><\/tr><\/tbody><\/table><\/figure><h2 class=\"wp-block-heading c42\" id=\"h.syd4m5ybpl6\"><span class=\"c26\">Aplica\u00e7\u00f5es de a\u00e7o AerMet 100<\/span><\/h2><ul class=\"wp-block-list c22 lst-kix_549gkzvqnf5a-0 start\"><li><span class=\"c3\">Aeroespacial<\/span><span class=\"c16\">: Trem de pouso, eixos de motores a jato<\/span><\/li>\n\n<li><span class=\"c3\">Defesa<\/span><span class=\"c16\">: Blindagem, componentes bal\u00edsticos<\/span><\/li>\n\n<li><span class=\"c3\">Energia<\/span><span class=\"c16\">: Eixos de transmiss\u00e3o<\/span><\/li>\n\n<li><span class=\"c3\">Industrial<\/span><span class=\"c16\">:Tubula\u00e7\u00e3o estrutural<\/span><\/li>\n\n<li><span class=\"c3\">Transporte<\/span><span>: Membros estruturais<\/span><\/li><\/ul><h2 class=\"wp-block-heading c7 c14\" id=\"h.vrtife2y7ry5\"><span class=\"c35\">A\u00e7o AerMet 100 <\/span><span class=\"c26\">Tratamento t\u00e9rmico<\/span><\/h2><h3 class=\"wp-block-heading c7 c14\" id=\"h.f725mzxvcte8\"><span class=\"c6\">Vis\u00e3o geral das etapas principais<\/span><\/h3><figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Est\u00e1gio<\/strong><\/td><td><strong>Par\u00e2metros-chave<\/strong><\/td><td><strong>Prop\u00f3sito<\/strong><\/td><\/tr><tr><td>Tratamento de solu\u00e7\u00f5es<\/td><td>885\u00b0C \u00b114\u00b0C por 1 hora (1625\u00b0F \u00b125\u00b0F)<\/td><td>Dissolver carbonetos, homogeneizar microestrutura.<\/td><\/tr><tr><td>Resfriamento<\/td><td>Ar\/\u00f3leo resfriado a 66\u00b0C (150\u00b0F) em 1\u20132 horas<\/td><td>Bloqueio na estrutura martens\u00edtica.<\/td><\/tr><tr><td>Tratamento pelo frio<\/td><td>-73\u00b0C por 1 hora (-100\u00b0F)<\/td><td>Aumente a tenacidade reduzindo a austenita retida.<\/td><\/tr><tr><td>Envelhecimento<\/td><td>482\u00b0C \u00b16\u00b0C por 5 horas (900\u00b0F \u00b110\u00b0F)<\/td><td>Precipitar fases secund\u00e1rias para otimizar a resist\u00eancia e a ductilidade.<\/td><\/tr><\/tbody><\/table><\/figure><h3 class=\"wp-block-heading c7 c14\" id=\"h.mnmwvssb680b\"><span class=\"c6\">1. Normalizando<\/span><\/h3><p class=\"c7\"><span>O a\u00e7o AerMet 100 \u00e9 normalizado por aquecimento at\u00e9 <\/span><span class=\"c3\">1650\u00b0F (899\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">uma hora<\/span><span>, permitindo ent\u00e3o que esfrie ao ar at\u00e9 a temperatura ambiente. Isso ajuda a restaurar as propriedades em \u00e1reas afetadas pela forja. Para melhor usinabilidade, um <\/span><span class=\"c3\">Recozimento de 16 horas a 1250\u00b0F (677\u00b0C)<\/span><span class=\"c16\">&nbsp;\u00e9 recomendado ap\u00f3s a normaliza\u00e7\u00e3o.<\/span><\/p><h3 class=\"wp-block-heading c7 c14\" id=\"h.lzflkbx80bpb\"><span class=\"c6\">2. Tratamento de solu\u00e7\u00e3o<\/span><\/h3><p class=\"c7\"><span>O AerMet 100 passa por um tratamento de solu\u00e7\u00e3o por aquecimento at\u00e9 <\/span><span class=\"c3\">1625\u00b0F \u00b125\u00b0F (885\u00b0C \u00b114\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">1 hora<\/span><span>&nbsp;em uma atmosfera neutra (v\u00e1cuo, banho de sal ou g\u00e1s inerte) para evitar a descarboneta\u00e7\u00e3o. Ap\u00f3s o aquecimento, a liga \u00e9 resfriada ao ar para <\/span><span class=\"c3\">150\u00b0F (66\u00b0C)<\/span><span>&nbsp;dentro de <\/span><span class=\"c3\">1-2 horas<\/span><span class=\"c16\">. Se\u00e7\u00f5es mais espessas (&gt;2\u2033 de di\u00e2metro ou chapa de 1\u2033 de espessura) devem ser temperadas em \u00f3leo para atender \u00e0s metas de resfriamento. Este processo dissolve carbonetos e prepara o material para transforma\u00e7\u00e3o martens\u00edtica.<\/span><\/p><h3 class=\"wp-block-heading c7 c14\" id=\"h.chb3r1do5s9i\"><span class=\"c6\">3. Tratamento a frio (resfriamento criog\u00eanico)<\/span><\/h3><p class=\"c7\"><span>Ap\u00f3s o tratamento da solu\u00e7\u00e3o, o AerMet 100 deve ser resfriado para <\/span><span class=\"c3\">-100\u00b0F (-73\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">pelo menos uma hora<\/span><span>. Esta etapa garante a transforma\u00e7\u00e3o martens\u00edtica completa e elimina a austenita retida, aumentando a tenacidade. Se ignorada, a tenacidade \u00e9 reduzida em cerca de <\/span><span class=\"c3\">15%<\/span><span>. Pular o tratamento pelo frio requer <\/span><span class=\"c3\">envelhecimento duplo a 900\u00b0F (482\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">5 horas<\/span><span class=\"c16\">&nbsp;duas vezes para compensar a perda de resist\u00eancia.<\/span><\/p><h3 class=\"wp-block-heading c7 c14\" id=\"h.7fllzv10zdn6\"><span class=\"c6\">4. Tratamento de envelhecimento (endurecimento por precipita\u00e7\u00e3o)<\/span><\/h3><p class=\"c7\"><span>O envelhecimento envolve o aquecimento do AerMet 100 para <\/span><span class=\"c3\">900\u00b0F \u00b110\u00b0F (482\u00b0C \u00b16\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">5 horas<\/span><span class=\"c16\">, seguido de resfriamento a ar. Este processo forma precipitados finos que aumentam a resist\u00eancia enquanto mant\u00eam a ductilidade. Os ajustes de temperatura de envelhecimento podem variar com base nos requisitos:<\/span><\/p><ul class=\"wp-block-list c22 lst-kix_cxsw2xsuy4lo-0 start\"><li><span>Em <\/span><span class=\"c3\">875\u00b0F (468\u00b0C)<\/span><span>\u00a0para <\/span><span class=\"c3\">5 horas<\/span><span>, a dureza atinge <\/span><span class=\"c3\">54,5\u201355,5 HRC<\/span><span class=\"c16\">, mas a resist\u00eancia diminui.<\/span><\/li>\n\n<li><span>Em <\/span><span class=\"c3\">925\u00b0F (496\u00b0C)<\/span><span>\u00a0para <\/span><span class=\"c3\">5 horas<\/span><span>, a dureza diminui para <\/span><span class=\"c3\">51,0\u201352,5 HRC<\/span><span class=\"c16\">, melhorando a ductilidade.<\/span><\/li><\/ul><h3 class=\"wp-block-heading c7 c14\" id=\"h.ndjspbzea2mq\"><span class=\"c6\">5. Recozimento<\/span><\/h3><p class=\"c7\"><span>Para amaciar o material para usinagem ou recupera\u00e7\u00e3o ap\u00f3s forjamento, o AerMet 100 pode ser recozido em <\/span><span class=\"c3\">1250\u00b0F (677\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">16 horas<\/span><span>. Isso produz uma dureza de <\/span><span class=\"c3\">\u226440 HRC<\/span><span class=\"c16\">, facilitando a usinagem.<\/span><\/p><h3 class=\"wp-block-heading c7 c14\" id=\"h.5ymrnwiljtj\"><span class=\"c6\">6. Alisamento<\/span><\/h3><p class=\"c7\"><span>O AerMet 100 sofre altera\u00e7\u00f5es m\u00ednimas de tamanho durante o tratamento t\u00e9rmico. No entanto, algumas pe\u00e7as podem precisar de endireitamento mec\u00e2nico para corrigir a distor\u00e7\u00e3o. O endireitamento deve ser feito ap\u00f3s o envelhecimento, mas antes da usinagem final. Para garantir resultados ideais, execute uma <\/span><span class=\"c3\">al\u00edvio do estresse em baixa temperatura<\/span><span>&nbsp;no <\/span><span class=\"c3\">350\u2013400\u00b0F (177\u2013204\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">5 horas<\/span><span class=\"c16\">&nbsp;antes de alisar.<\/span><\/p><ul class=\"wp-block-list c22 lst-kix_cauig5hextid-0 start\"><li><h3 id=\"h.puhsckqlcn70\" style=\"display:inline\"><span class=\"c6\">Risco de descarboneta\u00e7\u00e3o<\/span><\/h3><\/li><\/ul><p class=\"c7\"><span>O AerMet 100 \u00e9 propenso \u00e0 descarboneta\u00e7\u00e3o, que ocorre quando o carbono \u00e9 perdido da superf\u00edcie durante o tratamento t\u00e9rmico. Para minimizar esse risco, o tratamento t\u00e9rmico deve ser conduzido em um forno de atmosfera neutra, banho de sal ou v\u00e1cuo. A descarboneta\u00e7\u00e3o pode ser detectada comparando a dureza da superf\u00edcie e do n\u00facleo, garantindo que a diferen\u00e7a (\u0394HRC) n\u00e3o exceda <\/span><span class=\"c3\">2<\/span><span class=\"c16\">.<\/span><\/p><ul class=\"wp-block-list c22 lst-kix_lklctnh5mffi-0 start\"><li><h3 id=\"h.y1raw46un99j\" style=\"display:inline\"><span class=\"c6\">Considera\u00e7\u00f5es de p\u00f3s-processamento<\/span><\/h3><\/li><\/ul><p class=\"c7\"><span>Ap\u00f3s a usinagem, um <\/span><span class=\"c3\">al\u00edvio do estresse<\/span><span>&nbsp;no <\/span><span class=\"c3\">800\u00b0F (427\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">1\u20133 horas<\/span><span class=\"c16\">&nbsp;pode ser aplicado para reduzir tens\u00f5es residuais sem comprometer a resist\u00eancia. Esta etapa ajuda a melhorar o desempenho do material em aplica\u00e7\u00f5es finais.<\/span><\/p><h2 class=\"wp-block-heading c7 c14\" id=\"h.iqlexasshegj\"><span class=\"c26\">Processamento de a\u00e7o AerMet 100<\/span><\/h2><h3 class=\"wp-block-heading c7 c14\" id=\"h.kdfsm9apqf6y\"><span class=\"c6\">Forjamento<\/span><\/h3><p class=\"c7\"><span>O a\u00e7o AerMet 100 deve ser forjado a uma temperatura inicial de <\/span><span class=\"c3\">\u22642250\u00b0F (1232\u00b0C)<\/span><span>, com uma temperatura final de forjamento de <\/span><span class=\"c3\">\u22641650\u00b0F (899\u00b0C)<\/span><span class=\"c16\">. Ap\u00f3s o forjamento, o material deve passar por recozimento e normaliza\u00e7\u00e3o para restaurar suas propriedades e garantir desempenho ideal durante o processamento subsequente.<\/span><\/p><h3 class=\"wp-block-heading c7 c14\" id=\"h.gp3qaih7vm6u\"><span class=\"c6\">Usinagem<\/span><\/h3><p class=\"c7\"><span>O AerMet 100 \u00e9 mais desafiador de usinar do que <\/span><span class=\"c3\">A\u00e7o 4340<\/span><span>&nbsp;no <\/span><span class=\"c3\">CDH 38<\/span><span>. Para obter os melhores resultados, ferramentas de carboneto s\u00e3o recomendadas. A velocidade de corte deve variar de <\/span><span class=\"c3\">280 a 350 SFM<\/span><span>. Ap\u00f3s a usinagem de desbaste, \u00e9 essencial executar <\/span><span class=\"c3\">al\u00edvio do estresse<\/span><span>&nbsp;no <\/span><span class=\"c3\">800\u00b0F (427\u00b0C)<\/span><span>&nbsp;para <\/span><span class=\"c3\">1\u20133 horas<\/span><span>&nbsp;para reduzir tens\u00f5es residuais e melhorar a estabilidade do material para usinagem posterior.<\/span><\/p><h2 class=\"wp-block-heading c14 c31\" id=\"h.hjp06n97861v\"><span class=\"c26\">A\u00e7o certificado AerMet 100 de origem <\/span><\/h2><p class=\"c7\"><span class=\"c16\">No SteelPro Group, somos especializados em fornecer AerMet 100 de n\u00edvel aeroespacial que atende \u00e0s certifica\u00e7\u00f5es de defesa globais, garantindo que cada lote esteja alinhado com as rigorosas demandas. Nossa cadeia de suprimentos \u00e9 totalmente integrada, permitindo rastreabilidade completa da mat\u00e9ria-prima ao produto acabado.<\/span><\/p><p class=\"c7\"><span class=\"c16\">N\u00e3o deixe que os limites de material afetem seu projeto. Trabalhe com o SteelPro Group para obter o AerMet 100 \u2014 consistente e pronto para executar.<\/span><\/p><p><\/p>","protected":false},"excerpt":{"rendered":"<p>Master AerMet 100 Steel: propriedades, tratamento t\u00e9rmico e aplica\u00e7\u00f5es de defesa. Obtenha material certificado pela AMS 6532 com a expertise t\u00e9cnica do SteelPro Group.<\/p>","protected":false},"author":1,"featured_media":21788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","rank_math_lock_modified_date":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4308],"tags":[],"class_list":["post-21787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alloy-steel"],"acf":[],"_links":{"self":[{"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/posts\/21787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/comments?post=21787"}],"version-history":[{"count":0,"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/posts\/21787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/media\/21788"}],"wp:attachment":[{"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/media?parent=21787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/categories?post=21787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/steelprogroup.com\/pt\/wp-json\/wp\/v2\/tags?post=21787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}